{"id":161,"date":"2020-03-10T13:20:40","date_gmt":"2020-03-10T12:20:40","guid":{"rendered":"http:\/\/crieur-public.net\/?p=73"},"modified":"2024-09-26T16:45:18","modified_gmt":"2024-09-26T14:45:18","slug":"offener-brief-an-die-muslimische-welt","status":"publish","type":"post","link":"https:\/\/crieur-public.com\/en\/offener-brief-an-die-muslimische-welt\/","title":{"rendered":"Abdennour Bidar: Offener Brief an die muslimische Welt"},"content":{"rendered":"<h4>Als erstes Werk von dem in Frankreich sehr bekannten und viel beachteten Philosophen Abdennour Bidar liegt nun in deutscher Sprache das Buch \u201cOffener Brief an die muslimische Welt\u201d vor. In diesem setzt er sich, selbst Moslem, ebenso besorgt wie kritisch mit dem Zustand der muslimischen Welt im Zeichen des IS auseinander.<\/h4>\r\n<p><!--more-->Zugleich hinterfragt er die aus seiner Sicht nahezu spiegelbildlichen Schw\u00e4chen der westlichen Welt. Anlass f\u00fcr Bidar dieses Buch zu verfassen, waren die Attentate auf die Satirezeitschrift Charlie Hebdo und den j\u00fcdischen Supermarkt im Januar 2015. Bidar f\u00fchrt dazu in dem beigef\u00fcgten Filmbeitrag aus: \u201cIn der muslimischen Welt ist heute das, was als heilig betrachtet wird, zugleich unber\u00fchrbar, nicht diskutierbar. Hier dr\u00fcckt die Religion nicht die Dominanz Gottes gegen\u00fcber den Menschen aus, sondern wird vom Menschen zur Unterwerfung anderer Menschen genutzt\u2026. Das Verbrechen des modernen Westens ist es, dass er alle Verbindungen des Menschen zur Unendlichkeit innerhalb und au\u00dferhalb des Menschen gekappt hat. Den alten Religionen warf der Westen vor, blo\u00dfe Illusion zu sein, Opium des Volkes.&#8221; Einen Ausweg aus der Krise sieht Bidar im Entdecken einer gemeinschaftlichen Verantwortung f\u00fcr unsere Gesellschaft: &#8220;K\u00f6nnen wir gemeinsame Werte finden, die uns einander n\u00e4her bringen? Was k\u00f6nnen wir gemeinsam als heilig, als grundlegend definieren?&#8221; Erg\u00e4nzt und aktualisiert hat Bidar noch um ein Nachwort, das er Anfang August 2016 f\u00fcr die deutsche Fassung seines Buches geschrieben hat.Sein Buch wurde im Internet oder in Buchform von ca. 3 Millionen Menschen gelesen. In der Presse wurde sein Werk positiv aufgenommen, hier sind einige Stimmen:<\/p>\r\n<h4>T\u00e9l\u00e9rama :<\/h4>\r\n<p>Sein \u201eOffener Brief an die muslimische Welt \u201c ist ein vibrierender Aufruf zur Selbstkrik und zur Reform. Abdennour ( sein Vorname bedeutet: \u201eDiener des Lichts\u201c) Bidar ist ein Hoffnungstr\u00e4ger.<\/p>\r\n<h4>Liberation:<\/h4>\r\n<p>Nach der Meinung des Philosophen wollen die Terroristen uns gegeneinander aufhetzen, Muslime gegen nicht-Muslime sowie die B\u00fcrger gegen eine politische Klasse, die \u201eunf\u00e4hig sei, uns zu sch\u00fctzen\u201c.<\/p>\r\n<h4>La Croix:<\/h4>\r\n<p>Abdennour Bidar, der engagierte Mediator.<\/p>\r\n<h4>20 minutes :<\/h4>\r\n<p>Sein \u201eOffener Brief f\u00fcr die muslimische Welt \u201c wurde von Millionen von Menschen nach den Attentaten gelesen. Ein Echo ohne Pr\u00e4zedenzfall.<\/p>\r\n<h4>Le Figaro:<\/h4>\r\n<p>In einem Text, der auch in mehreren europ\u00e4ischen Tageszeitungen ver\u00f6ffentlicht wurde, warnt der Intellektuelle vor der Falle des \u201eislamischen Staates\u201c und ruft zur Fortentwicklung des Islams auf.<\/p>\r\n\r\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\r\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" style=\"background-color: #8c141a;\" href=\"https:\/\/www.amazon.de\/Offener-Brief-die-muslimische-Welt\/dp\/3981506251\/ref=tmm_pap_swatch_0?_encoding=UTF8&amp;qid=1584012728&amp;sr=8-1\" target=\"_blank\" rel=\"noreferrer noopener\">Bei Amazon kaufen<\/a><\/div>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Als erstes Werk von dem in Frankreich sehr bekannten und viel beachteten Philosophen Abdennour Bidar liegt nun in deutscher Sprache das Buch \u201cOffener Brief an die muslimische Welt\u201d vor. In diesem setzt er sich, selbst Moslem, ebenso besorgt wie kritisch mit dem Zustand der muslimischen Welt im Zeichen des IS auseinander.<\/p>\n","protected":false},"author":2,"featured_media":381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177],"tags":[],"class_list":["post-161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sachbuecher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public\" \/>\n<meta property=\"og:description\" content=\"Als erstes Werk von dem in Frankreich sehr bekannten und viel beachteten Philosophen Abdennour Bidar liegt nun in deutscher Sprache das Buch \u201cOffener Brief an die muslimische Welt\u201d vor. In diesem setzt er sich, selbst Moslem, ebenso besorgt wie kritisch mit dem Zustand der muslimischen Welt im Zeichen des IS auseinander.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/\" \/>\n<meta property=\"og:site_name\" content=\"Crieur Public\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T12:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T14:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion Crieur Public\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Crieur Public\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/\"},\"author\":{\"name\":\"Redaktion Crieur Public\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\"},\"headline\":\"Abdennour Bidar: Offener Brief an die muslimische Welt\",\"datePublished\":\"2020-03-10T12:20:40+00:00\",\"dateModified\":\"2024-09-26T14:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/\"},\"wordCount\":396,\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-A_Bidar.jpg\",\"articleSection\":[\"Sachb\u00fccher\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/\",\"name\":\"Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-A_Bidar.jpg\",\"datePublished\":\"2020-03-10T12:20:40+00:00\",\"dateModified\":\"2024-09-26T14:45:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-A_Bidar.jpg\",\"contentUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-A_Bidar.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/offener-brief-an-die-muslimische-welt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/crieur-public.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abdennour Bidar: Offener Brief an die muslimische Welt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"name\":\"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag\",\"description\":\"Deutsch-franz\u00f6sischer Verlag\",\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crieur-public.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\",\"name\":\"Franco-German publishing house\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"contentUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"width\":1260,\"height\":406,\"caption\":\"Franco-German publishing house\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\",\"name\":\"Redaktion Crieur Public\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"caption\":\"Redaktion Crieur Public\"},\"url\":\"https:\\\/\\\/crieur-public.com\\\/en\\\/author\\\/redaktion-crieur-public\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/","og_locale":"en_US","og_type":"article","og_title":"Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public","og_description":"Als erstes Werk von dem in Frankreich sehr bekannten und viel beachteten Philosophen Abdennour Bidar liegt nun in deutscher Sprache das Buch \u201cOffener Brief an die muslimische Welt\u201d vor. In diesem setzt er sich, selbst Moslem, ebenso besorgt wie kritisch mit dem Zustand der muslimischen Welt im Zeichen des IS auseinander.","og_url":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/","og_site_name":"Crieur Public","article_published_time":"2020-03-10T12:20:40+00:00","article_modified_time":"2024-09-26T14:45:18+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg","type":"image\/jpeg"}],"author":"Redaktion Crieur Public","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redaktion Crieur Public","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#article","isPartOf":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/"},"author":{"name":"Redaktion Crieur Public","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929"},"headline":"Abdennour Bidar: Offener Brief an die muslimische Welt","datePublished":"2020-03-10T12:20:40+00:00","dateModified":"2024-09-26T14:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/"},"wordCount":396,"publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"image":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg","articleSection":["Sachb\u00fccher"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/","url":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/","name":"Abdennour Bidar: Offener Brief an die muslimische Welt - Crieur Public","isPartOf":{"@id":"https:\/\/crieur-public.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#primaryimage"},"image":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg","datePublished":"2020-03-10T12:20:40+00:00","dateModified":"2024-09-26T14:45:18+00:00","breadcrumb":{"@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#primaryimage","url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg","contentUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-A_Bidar.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/crieur-public.com\/offener-brief-an-die-muslimische-welt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/crieur-public.com\/"},{"@type":"ListItem","position":2,"name":"Abdennour Bidar: Offener Brief an die muslimische Welt"}]},{"@type":"WebSite","@id":"https:\/\/crieur-public.com\/#website","url":"https:\/\/crieur-public.com\/","name":"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag","description":"Deutsch-franz\u00f6sischer Verlag","publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crieur-public.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/crieur-public.com\/#organization","name":"Franco-German publishing house","url":"https:\/\/crieur-public.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/","url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","contentUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","width":1260,"height":406,"caption":"Franco-German publishing house"},"image":{"@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929","name":"Redaktion Crieur Public","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","caption":"Redaktion Crieur Public"},"url":"https:\/\/crieur-public.com\/en\/author\/redaktion-crieur-public\/"}]}},"_links":{"self":[{"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/posts\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/comments?post=161"}],"version-history":[{"count":2,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/posts\/161\/revisions"}],"predecessor-version":[{"id":473,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/posts\/161\/revisions\/473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/media\/381"}],"wp:attachment":[{"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/media?parent=161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/categories?post=161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crieur-public.com\/en\/wp-json\/wp\/v2\/tags?post=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}