{"id":159,"date":"2020-03-25T11:55:05","date_gmt":"2020-03-25T10:55:05","guid":{"rendered":"http:\/\/crieur-public.net\/?p=52"},"modified":"2024-09-26T11:54:24","modified_gmt":"2024-09-26T09:54:24","slug":"die-welt-empfiehlt-gehaengt-in-auschwitz","status":"publish","type":"post","link":"https:\/\/crieur-public.com\/fr\/die-welt-empfiehlt-gehaengt-in-auschwitz\/","title":{"rendered":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d"},"content":{"rendered":"<p><strong>LESEEMPFEHLUNG\u00a0in\u00a0der Welt vom\u00a08. Februar 2020:<\/strong><\/p>\n<p>\u201cWie wichtig es ist, an die Untaten zu erinnern, die die Deutschen mit dem Holocaust begangen haben. Ein Buch, das dies eindr\u00fccklich reflektiert, ist die Geschichte des\u00a0j\u00fcdischen Berufsboxers Sim Kessel, der in der R\u00e9sistance war, inhaftiert und nach Auschwitz deportiert wurde, wo er geh\u00e4ngt werden sollte und von seinem Henker, der ebenfalls Boxer war, gerettet wurde: \u201eGeh\u00e4ngt in Auschwitz. Die Autobiographie eines \u00dcberlebenden\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LESEEMPFEHLUNG\u00a0in\u00a0der Welt vom\u00a08. Februar 2020: \u201cWie wichtig es ist, an die Untaten zu erinnern, die die Deutschen mit dem Holocaust begangen haben. Ein Buch, das dies eindr\u00fccklich reflektiert, ist die Geschichte des\u00a0j\u00fcdischen Berufsboxers Sim Kessel, der in der R\u00e9sistance war, inhaftiert und nach Auschwitz deportiert wurde, wo er geh\u00e4ngt werden sollte und von seinem Henker, &hellip; <a href=\"https:\/\/crieur-public.com\/fr\/die-welt-empfiehlt-gehaengt-in-auschwitz\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[228],"tags":[6,40,5],"class_list":["post-159","post","type-post","status-publish","format-standard","hentry","category-news","tag-auschwitz","tag-drancy","tag-sim-kessel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public\" \/>\n<meta property=\"og:description\" content=\"LESEEMPFEHLUNG\u00a0in\u00a0der Welt vom\u00a08. Februar 2020: \u201cWie wichtig es ist, an die Untaten zu erinnern, die die Deutschen mit dem Holocaust begangen haben. Ein Buch, das dies eindr\u00fccklich reflektiert, ist die Geschichte des\u00a0j\u00fcdischen Berufsboxers Sim Kessel, der in der R\u00e9sistance war, inhaftiert und nach Auschwitz deportiert wurde, wo er geh\u00e4ngt werden sollte und von seinem Henker, &hellip; Continuer la lecture de Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"Crieur Public\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T10:55:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T09:54:24+00:00\" \/>\n<meta name=\"author\" content=\"Redaktion Crieur Public\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Crieur Public\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/\"},\"author\":{\"name\":\"Redaktion Crieur Public\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\"},\"headline\":\"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d\",\"datePublished\":\"2020-03-25T10:55:05+00:00\",\"dateModified\":\"2024-09-26T09:54:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/\"},\"wordCount\":82,\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"keywords\":[\"Auschwitz\",\"Drancy\",\"Sim Kessel\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/\",\"name\":\"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\"},\"datePublished\":\"2020-03-25T10:55:05+00:00\",\"dateModified\":\"2024-09-26T09:54:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/die-welt-empfiehlt-gehaengt-in-auschwitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/crieur-public.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"name\":\"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag\",\"description\":\"Deutsch-franz\u00f6sischer Verlag\",\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crieur-public.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\",\"name\":\"Maison d'\u00e9dition franco-allemande\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"contentUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"width\":1260,\"height\":406,\"caption\":\"Maison d'\u00e9dition franco-allemande\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\",\"name\":\"Redaktion Crieur Public\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"caption\":\"Redaktion Crieur Public\"},\"url\":\"https:\\\/\\\/crieur-public.com\\\/fr\\\/author\\\/redaktion-crieur-public\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/","og_locale":"fr_FR","og_type":"article","og_title":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public","og_description":"LESEEMPFEHLUNG\u00a0in\u00a0der Welt vom\u00a08. Februar 2020: \u201cWie wichtig es ist, an die Untaten zu erinnern, die die Deutschen mit dem Holocaust begangen haben. Ein Buch, das dies eindr\u00fccklich reflektiert, ist die Geschichte des\u00a0j\u00fcdischen Berufsboxers Sim Kessel, der in der R\u00e9sistance war, inhaftiert und nach Auschwitz deportiert wurde, wo er geh\u00e4ngt werden sollte und von seinem Henker, &hellip; Continuer la lecture de Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d &rarr;","og_url":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/","og_site_name":"Crieur Public","article_published_time":"2020-03-25T10:55:05+00:00","article_modified_time":"2024-09-26T09:54:24+00:00","author":"Redaktion Crieur Public","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaktion Crieur Public"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/#article","isPartOf":{"@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/"},"author":{"name":"Redaktion Crieur Public","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929"},"headline":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d","datePublished":"2020-03-25T10:55:05+00:00","dateModified":"2024-09-26T09:54:24+00:00","mainEntityOfPage":{"@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/"},"wordCount":82,"publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"keywords":["Auschwitz","Drancy","Sim Kessel"],"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/","url":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/","name":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d - Crieur Public","isPartOf":{"@id":"https:\/\/crieur-public.com\/#website"},"datePublished":"2020-03-25T10:55:05+00:00","dateModified":"2024-09-26T09:54:24+00:00","breadcrumb":{"@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/crieur-public.com\/die-welt-empfiehlt-gehaengt-in-auschwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/crieur-public.com\/"},{"@type":"ListItem","position":2,"name":"Die Welt empfiehlt \u201cGeh\u00e4ngt in Auschwitz\u201d"}]},{"@type":"WebSite","@id":"https:\/\/crieur-public.com\/#website","url":"https:\/\/crieur-public.com\/","name":"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag","description":"Deutsch-franz\u00f6sischer Verlag","publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crieur-public.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/crieur-public.com\/#organization","name":"Maison d'\u00e9dition franco-allemande","url":"https:\/\/crieur-public.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/","url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","contentUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","width":1260,"height":406,"caption":"Maison d'\u00e9dition franco-allemande"},"image":{"@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929","name":"Redaktion Crieur Public","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","caption":"Redaktion Crieur Public"},"url":"https:\/\/crieur-public.com\/fr\/author\/redaktion-crieur-public\/"}]}},"_links":{"self":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/comments?post=159"}],"version-history":[{"count":2,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/159\/revisions"}],"predecessor-version":[{"id":395,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/159\/revisions\/395"}],"wp:attachment":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/media?parent=159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/categories?post=159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/tags?post=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}