{"id":164,"date":"2020-03-10T14:55:21","date_gmt":"2020-03-10T13:55:21","guid":{"rendered":"http:\/\/crieur-public.net\/?p=99"},"modified":"2024-09-26T16:45:17","modified_gmt":"2024-09-26T14:45:17","slug":"pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit","status":"publish","type":"post","link":"https:\/\/crieur-public.com\/fr\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/","title":{"rendered":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit"},"content":{"rendered":"<h4>Die Originalausgabe \u201eZoos humains\u201c wurde von Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire erarbeitet.<\/h4>\r\n<p>Das auch heute noch bewusst oder unterbewusst verbreitete Bild des Wilden, des \u201eNegers\u201c, des Exoten wurde in der Zeit von 1860 bis 1930 in Europa, Amerika und Japan durch Menschenzoos gepr\u00e4gt. Millionen von Menschen gingen \u201emit Kind und Kegel\u201c in den Zoo oder zu den Ausstellungen, um erstmals in ihrem Leben \u201edie Wilden\u201c zu sehen. Diese wurden hinter Z\u00e4unen ausgestellt, wie Tiere. Oftmals wurden diese Menschen auch zwischen den K\u00e4figen mit wilden Tieren platziert . Gelegentlich fand sich auch der entsprechende Hinweis \u201eBitte nicht f\u00fcttern\u201c.<!--more--><\/p>\r\n<figure id=\"attachment_104\" aria-describedby=\"caption-attachment-104\" style=\"width: 225px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-104 size-full\" src=\"http:\/\/2024.crieur-public.com\/wp-content\/uploads\/2020\/03\/image-4.png\" alt=\"\" width=\"225\" height=\"300\" \/><figcaption id=\"caption-attachment-104\" class=\"wp-caption-text\">Plakat-Kolonialausstellung Stuttgart 1928<\/figcaption><\/figure>\r\n<p>Im \u00f6ffentlichen Bewusstsein sind diese in Deutschland insbesondere von Carl Hagenbeck wirtschaftlich sehr erfolgreich organisierten \u201eV\u00f6lkerschauen\u201c fast nicht mehr pr\u00e4sent. Doch spielten diese eine wesentliche Rolle im Kolonialzeitalter. Sie befriedigten das Interesse an fremden Kulturen in einer rassistischen Form. Der Andere, der Ausgestellte,\u00a0 war unterlegen, der Besucher war \u00fcberlegen. Herr versus minderer Mensch &#8211; so ist es kein sehr gro\u00dfer Schritt mehr zum \u00ab\u00a0Herrenmenschen\u00a0\u00bb, den \u00ab\u00a0Herrenrassen\u00a0\u00bb und den \u00ab\u00a0Untermenschen\u00a0\u00bb. Die Ausstellungen schufen oder best\u00e4rkten Generationen \u00fcbergreifende, bis heute vorhandene rassistische Vorurteile.<\/p>\r\n\r\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\r\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" style=\"background-color: #8c141a;\" href=\"https:\/\/www.amazon.de\/MenschenZoos-Schaufenster-Unmenschlichkeit-Sandrine-Lemaire\/dp\/3981506200\/ref=sr_1_1?__mk_de_DE=\u00c5M\u00c5\u017d\u00d5\u00d1&amp;keywords=Menschenzoos&amp;qid=1583937800&amp;sr=8-1\" target=\"_blank\" rel=\"noreferrer noopener\">Bei Amazon kaufen<\/a><\/div>\r\n<\/div>\r\n\r\n<h3>Ausstellung \u00ab\u00a0Menschen Zoos &#8211; Schaufenster der Unmenschlichkeit\u00a0\u00bb<\/h3>\r\n<p>Die Ausstellung \u00ab\u00a0Menschen Zoos &#8211; Schaufenster der Unmenschlichkeit\u00a0\u00bb pr\u00e4sentierte im Herbst 2015 in der Friedrich-Schiller-Universit\u00e4t Jena erstmals auf deutschem Boden Dokumente zu diesem Thema. Dieses Video ist eine Dokumentation der Ausstellung. <iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/VH6q07tKOzI?si=0ZPtMUBPWR--uWdH\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Originalausgabe \u201eZoos humains\u201c wurde von Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire erarbeitet. Das auch heute noch bewusst oder unterbewusst verbreitete Bild des Wilden, des \u201eNegers\u201c, des Exoten wurde in der Zeit von 1860 bis 1930 in Europa, Amerika und Japan durch Menschenzoos gepr\u00e4gt. Millionen von Menschen gingen \u201emit Kind &hellip; <a href=\"https:\/\/crieur-public.com\/fr\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":385,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177],"tags":[],"class_list":["post-164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sachbuecher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public\" \/>\n<meta property=\"og:description\" content=\"Die Originalausgabe \u201eZoos humains\u201c wurde von Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire erarbeitet. Das auch heute noch bewusst oder unterbewusst verbreitete Bild des Wilden, des \u201eNegers\u201c, des Exoten wurde in der Zeit von 1860 bis 1930 in Europa, Amerika und Japan durch Menschenzoos gepr\u00e4gt. Millionen von Menschen gingen \u201emit Kind &hellip; Continuer la lecture de Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Crieur Public\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T13:55:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T14:45:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion Crieur Public\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Crieur Public\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/\"},\"author\":{\"name\":\"Redaktion Crieur Public\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\"},\"headline\":\"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit\",\"datePublished\":\"2020-03-10T13:55:21+00:00\",\"dateModified\":\"2024-09-26T14:45:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-Menschenzoos.jpg\",\"articleSection\":[\"Sachb\u00fccher\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/\",\"name\":\"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-Menschenzoos.jpg\",\"datePublished\":\"2020-03-10T13:55:21+00:00\",\"dateModified\":\"2024-09-26T14:45:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-Menschenzoos.jpg\",\"contentUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Buecher-Teaser-Menschenzoos.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/crieur-public.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#website\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"name\":\"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag\",\"description\":\"Deutsch-franz\u00f6sischer Verlag\",\"publisher\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crieur-public.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#organization\",\"name\":\"Maison d'\u00e9dition franco-allemande\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"contentUrl\":\"https:\\\/\\\/crieur-public.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-les-editions-du-crieur-public-logo.png\",\"width\":1260,\"height\":406,\"caption\":\"Maison d'\u00e9dition franco-allemande\"},\"image\":{\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crieur-public.com\\\/#\\\/schema\\\/person\\\/69274f729a97dc7cb0efff2032cbc929\",\"name\":\"Redaktion Crieur Public\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g\",\"caption\":\"Redaktion Crieur Public\"},\"url\":\"https:\\\/\\\/crieur-public.com\\\/fr\\\/author\\\/redaktion-crieur-public\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/","og_locale":"fr_FR","og_type":"article","og_title":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public","og_description":"Die Originalausgabe \u201eZoos humains\u201c wurde von Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire erarbeitet. Das auch heute noch bewusst oder unterbewusst verbreitete Bild des Wilden, des \u201eNegers\u201c, des Exoten wurde in der Zeit von 1860 bis 1930 in Europa, Amerika und Japan durch Menschenzoos gepr\u00e4gt. Millionen von Menschen gingen \u201emit Kind &hellip; Continuer la lecture de Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit &rarr;","og_url":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/","og_site_name":"Crieur Public","article_published_time":"2020-03-10T13:55:21+00:00","article_modified_time":"2024-09-26T14:45:17+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg","type":"image\/jpeg"}],"author":"Redaktion Crieur Public","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaktion Crieur Public","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#article","isPartOf":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/"},"author":{"name":"Redaktion Crieur Public","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929"},"headline":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit","datePublished":"2020-03-10T13:55:21+00:00","dateModified":"2024-09-26T14:45:17+00:00","mainEntityOfPage":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/"},"wordCount":257,"publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"image":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#primaryimage"},"thumbnailUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg","articleSection":["Sachb\u00fccher"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/","url":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/","name":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit - Crieur Public","isPartOf":{"@id":"https:\/\/crieur-public.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#primaryimage"},"image":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#primaryimage"},"thumbnailUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg","datePublished":"2020-03-10T13:55:21+00:00","dateModified":"2024-09-26T14:45:17+00:00","breadcrumb":{"@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#primaryimage","url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg","contentUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2020\/03\/Buecher-Teaser-Menschenzoos.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/crieur-public.com\/pascal-blanchard-nicolas-bancel-gilles-boetsch-eric-deroo-und-sandrine-lemaire-menschenzoos-schaufenster-der-unmenschlichkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/crieur-public.com\/"},{"@type":"ListItem","position":2,"name":"Pascal Blanchard, Nicolas Bancel, Gilles Bo\u00ebtsch, Eric Deroo und Sandrine Lemaire: Menschenzoos \u2013\u00a0Schaufenster der Unmenschlichkeit"}]},{"@type":"WebSite","@id":"https:\/\/crieur-public.com\/#website","url":"https:\/\/crieur-public.com\/","name":"Crieur Public - Der \u00f6ffentliche Ausrufer \u00b7 Deutsch-franz\u00f6sischer Verlag","description":"Deutsch-franz\u00f6sischer Verlag","publisher":{"@id":"https:\/\/crieur-public.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crieur-public.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/crieur-public.com\/#organization","name":"Maison d'\u00e9dition franco-allemande","url":"https:\/\/crieur-public.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/","url":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","contentUrl":"https:\/\/crieur-public.com\/wp-content\/uploads\/2024\/03\/cropped-les-editions-du-crieur-public-logo.png","width":1260,"height":406,"caption":"Maison d'\u00e9dition franco-allemande"},"image":{"@id":"https:\/\/crieur-public.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/crieur-public.com\/#\/schema\/person\/69274f729a97dc7cb0efff2032cbc929","name":"Redaktion Crieur Public","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efe35bc6014edfbdfd9d3c68f8f40acd1507e2ceefcbd32ac99a6075ac15232d?s=96&d=mm&r=g","caption":"Redaktion Crieur Public"},"url":"https:\/\/crieur-public.com\/fr\/author\/redaktion-crieur-public\/"}]}},"_links":{"self":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/comments?post=164"}],"version-history":[{"count":5,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/164\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/posts\/164\/revisions\/478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/media\/385"}],"wp:attachment":[{"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/media?parent=164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/categories?post=164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crieur-public.com\/fr\/wp-json\/wp\/v2\/tags?post=164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}